{"id":12317,"date":"2019-02-01T21:22:55","date_gmt":"2019-02-01T21:22:55","guid":{"rendered":"https:\/\/hangar.com.pt\/?p=12317"},"modified":"2025-08-09T11:36:28","modified_gmt":"2025-08-09T10:36:28","slug":"sunny-drake","status":"publish","type":"post","link":"https:\/\/hangar.com.pt\/en\/sunny-drake\/","title":{"rendered":"Sunny Drake"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_empty_space height=&#8221;5px&#8221;][vc_separator color=&#8221;black&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<div style=\"text-align: justify;\">\n<p>Sunny Drake (Austr\u00e1lia) \u00e9 um dramaturgo, criador e int\u00e9rprete de teatro. Os seus trabalhos teatrais foram apresentados em 55 cidades do Canad\u00e1, Austr\u00e1lia, Estados Unidos e Europa, trazendo um trabalho transformador e inventivo para uma ampla gama de audi\u00eancias, desde senhoras idosas em teatros regionais a queers em armaz\u00e9ns underground. As suas pe\u00e7as foram traduzidas para 4 idiomas. Ele esteve em resid\u00eancia com \/ trabalhou com v\u00e1rias companhias, incluindo o Stratford Playwrights Retreat (2018), National Arts Centre\u2019s The Collaborations (2018\/19), Theatre Passe Muraille (2018\/19), Nightswimming (2018), Factory Theatre (2017), Yaddo (New York, 2018), Buddies in Bad Times Theatre (2016) e o Playwrights Theatre Centre\u2019s WrightSpace (2016). Drake nasceu na Austr\u00e1lia em Jagera-Turrbal (Brisbane) e, desde 2011, vive em Toronto como colono na terra do Mississauga de New Credit, Huron-Wendat, Haudenosaunee, Anishinaabe e outros. Tem seis novos trabalhos de teatro atualmente em desenvolvimento, que podem ser vistos em www.sunnydrake.com.<\/p>\n<p>No Hangar, Sunny ir em CHILD-ISH, uma pe\u00e7a textual extra\u00edda de entrevistas com crian\u00e7as sobre amor e namoro. As palavras exatas das crian\u00e7as s\u00e3o recontextualizadas em situa\u00e7\u00f5es adultas para atores adultos, com resultados surpreendentes, hilanriantes e emocionantes. CHILD-ISH transforma a forma como vemos o amor, as crian\u00e7as e os adultos.<\/p>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;5px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_masonry_media_grid initial_loading_animation=&#8221;none&#8221; grid_id=&#8221;vc_gid:1549361481934-c698d85b-b865-7&#8243; include=&#8221;12321&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Janeiro<\/p>\n","protected":false},"author":8,"featured_media":12322,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168],"tags":[241,286],"class_list":["post-12317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portfolios","tag-2019-en","tag-previous"],"_links":{"self":[{"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/posts\/12317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/comments?post=12317"}],"version-history":[{"count":1,"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/posts\/12317\/revisions"}],"predecessor-version":[{"id":18273,"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/posts\/12317\/revisions\/18273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/media\/12322"}],"wp:attachment":[{"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/media?parent=12317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/categories?post=12317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/tags?post=12317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}