{"id":11836,"date":"2018-11-08T17:18:21","date_gmt":"2018-11-08T17:18:21","guid":{"rendered":"https:\/\/hangar.com.pt\/?p=11836"},"modified":"2022-10-02T11:40:47","modified_gmt":"2022-10-02T10:40:47","slug":"ateliers-livres-natal-no-mini-hangar-2018","status":"publish","type":"post","link":"https:\/\/hangar.com.pt\/en\/ateliers-livres-natal-no-mini-hangar-2018\/","title":{"rendered":"ATELIERS LIVRES | NATAL NO MINI-HANGAR"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_empty_space height=&#8221;5px&#8221;][vc_separator color=&#8221;black&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;2\/3&#8243;][vc_column_text]<strong>ATELIER LIVRE l PRINC\u00cdPIO, MEIO E FIM<\/strong> \u2013 artes visuais e performance<\/p>\n<p>Onde \u00e9 o ponto de partida e o de chegada? Que caminho escolhemos para ir de um ponto ao outro, e o que acontece no percurso? Neste Atelier, inspirados pela ideia de \u201cArte Caminhada\u201d, e com base nas cria\u00e7\u00f5es de alguns artistas, vamos explorar o espa\u00e7o e o tempo, desenhar caminhos e criar movimentos. Experimentar diferentes passos e gestos, materiais e objetos, velocidades e planos, que nos v\u00e3o ajudar a construir uma travessia cheia de encontros e descobertas.<\/p>\n<p>Sempre a caminhar, entre paragens e contempla\u00e7\u00f5es, este atelier prop\u00f5em a explora\u00e7\u00e3o de diferentes pr\u00e1ticas art\u00edsticas, desde a performance, o happening, o desenho, a pintura, a escultura e a instala\u00e7\u00e3o, para estimular e desenvolver v\u00e1rias linguagens e processos criativos.<\/p>\n<p>&nbsp;<\/p>\n<p>Andaime Cooperativa Cultural, em colabora\u00e7\u00e3o com o Hangar &#8211; Centro de Investiga\u00e7\u00e3o Art\u00edstica[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;11837&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=&#8221;Detalhes&#8221; font_container=&#8221;tag:h4|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;black&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<strong>Data e Hora:<\/strong> 17 a 21 de dezembro 2018 | segunda a sexta | 9h30 \u00e0s 17h00<br \/>\n<strong>P\u00fablico-alvo:<\/strong> 5 aos 12 anos<br \/>\n<strong>Local:<\/strong> MINI-HANGAR | Rua Damasceno Monteiro, 12 (Gra\u00e7a)<br \/>\n<strong>Inscri\u00e7\u00f5es:<\/strong> geral@hangar.com.pt | 21 887 1481<br \/>\n<strong>Conce\u00e7\u00e3o e orienta\u00e7\u00e3o:<\/strong> Ana Teresa Magalh\u00e3es e Margarida Chambel para Andaime Cooperativa Cultural[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<strong>PRE\u00c7OS:<\/strong><br \/>\n1 semana: 90 \u20ac \/ crian\u00e7a<br \/>\n1 dia: 20 \u20ac \/ crian\u00e7a<br \/>\n1\/2 dia: 10\u20ac \/ crian\u00e7a<br \/>\nInclui materiais e seguro de acidentes pessoais.<\/p>\n<p>Desconto de 20% para s\u00f3cios.<br \/>\nSem Alimenta\u00e7\u00e3o (\u00e9 da responsabilidade dos educandos o lanchinho da manh\u00e3, almo\u00e7o e lanche).<br \/>\nO Mini-Hangar responsabiliza se por dar mimos e frutinhas da \u00e9poca!<br \/>\nN\u00ba de participantes: M\u00ednimo de 7 e m\u00e1ximo de 15.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=&#8221;Concep\u00e7\u00e3o e Orienta\u00e7\u00e3o&#8221; font_container=&#8221;tag:h4|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;black&#8221;][vc_column_text]<strong>ANDAIME<\/strong><\/p>\n<p>Quem \u00e9 a Andaime? Formada no ver\u00e3o de 2016, a Andaime \u00e9 uma cooperativa cultural que atua em tr\u00eas grandes eixos: Arte, Ambiente e Educa\u00e7\u00e3o. \u00c9 formada por uma equipa de artistas com experi\u00eancia nas \u00e1reas da educa\u00e7\u00e3o art\u00edstica e media\u00e7\u00e3o cultural, com trabalho desenvolvido em escolas, servi\u00e7os educativos de museus, centros de arte, espa\u00e7os culturais e bairros sociais. A Andaime nasceu de quem acredita que a educa\u00e7\u00e3o ambiental e art\u00edstica s\u00e3o vias prof\u00edcuas para a consciencializa\u00e7\u00e3o da necessidade de proteger o meio ambiente e o patrim\u00f3nio cultural em prol do desenvolvimento saud\u00e1vel dos indiv\u00edduos e da sustentabilidade do Planeta.<\/p>\n<p>ANDAIME COOPERATIVA CULTURAL | Email: <a href=\"mailto:andaimecooperativacultural@gmail.com\" target=\"_blank\" rel=\"noopener noreferrer\">andaimecooperativacultural@<wbr \/>gmail.com<\/a> | Tlm: 917924862\/ 934490950<\/p>\n<div class=\"m_-7798524411133956146gmail-vc_row m_-7798524411133956146gmail-wpb_row m_-7798524411133956146gmail-vc_row-fluid\"><\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>December 17th to 21st 2018<\/p>\n","protected":false},"author":8,"featured_media":11838,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[159,165],"tags":[242,286],"class_list":["post-11836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mini-hangar-en","category-news","tag-2018-en","tag-previous"],"_links":{"self":[{"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/posts\/11836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/comments?post=11836"}],"version-history":[{"count":3,"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/posts\/11836\/revisions"}],"predecessor-version":[{"id":21032,"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/posts\/11836\/revisions\/21032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/media\/11838"}],"wp:attachment":[{"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/media?parent=11836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/categories?post=11836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/tags?post=11836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}