{"id":25981,"date":"2024-06-25T20:40:54","date_gmt":"2024-06-25T19:40:54","guid":{"rendered":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg"},"modified":"2024-06-25T20:40:54","modified_gmt":"2024-06-25T19:40:54","slug":"sieglinde-wittwer-watercolor_sw1-2","status":"inherit","type":"attachment","link":"https:\/\/hangar.com.pt\/en\/sieglinde-wittwer\/sieglinde-wittwer-watercolor_sw1-2\/","title":{"rendered":"Sieglinde Wittwer &#8211; watercolor_SW1"},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-25981","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>HANGAR - Centro de Investiga\u00e7\u00e3o Art\u00edstica - Sieglinde Wittwer - watercolor_SW1<\/title>\n<meta name=\"description\" content=\"Exposi\u00e7\u00f5es, Workshops, Ateliers. Resid\u00eancias para artistas e alojamento criativo. Rua Damasceno Monteiro, 12 Lisboa, Portugal Sieglinde Wittwer - watercolor_SW1 - HANGAR\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HANGAR - Centro de Investiga\u00e7\u00e3o Art\u00edstica - Sieglinde Wittwer - watercolor_SW1\" \/>\n<meta property=\"og:description\" content=\"Exposi\u00e7\u00f5es, Workshops, Ateliers. Resid\u00eancias para artistas e alojamento criativo. Rua Damasceno Monteiro, 12 Lisboa, Portugal Sieglinde Wittwer - watercolor_SW1 - HANGAR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg\" \/>\n<meta property=\"og:site_name\" content=\"HANGAR\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1533\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg\",\"url\":\"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg\",\"name\":\"HANGAR - Centro de Investiga\u00e7\u00e3o Art\u00edstica - Sieglinde Wittwer - watercolor_SW1\",\"isPartOf\":{\"@id\":\"https:\/\/hangar.com.pt\/#website\"},\"datePublished\":\"2024-06-25T19:40:54+00:00\",\"dateModified\":\"2024-06-25T19:40:54+00:00\",\"description\":\"Exposi\u00e7\u00f5es, Workshops, Ateliers. Resid\u00eancias para artistas e alojamento criativo. Rua Damasceno Monteiro, 12 Lisboa, Portugal Sieglinde Wittwer - watercolor_SW1 - HANGAR\",\"breadcrumb\":{\"@id\":\"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/hangar.com.pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sieglinde Wittwer\",\"item\":\"https:\/\/hangar.com.pt\/en\/sieglinde-wittwer\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sieglinde Wittwer &#8211; watercolor_SW1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hangar.com.pt\/#website\",\"url\":\"https:\/\/hangar.com.pt\/\",\"name\":\"HANGAR\",\"description\":\"Centro de Investiga\u00e7\u00e3o Art\u00edstica\",\"publisher\":{\"@id\":\"https:\/\/hangar.com.pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hangar.com.pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hangar.com.pt\/#organization\",\"name\":\"HANGAR\",\"url\":\"https:\/\/hangar.com.pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/hangar.com.pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hangar.com.pt\/wp-content\/uploads\/2017\/03\/Hangar-Logo-02_SMALL_Mail.jpg\",\"contentUrl\":\"https:\/\/hangar.com.pt\/wp-content\/uploads\/2017\/03\/Hangar-Logo-02_SMALL_Mail.jpg\",\"width\":300,\"height\":164,\"caption\":\"HANGAR\"},\"image\":{\"@id\":\"https:\/\/hangar.com.pt\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HANGAR - Centro de Investiga\u00e7\u00e3o Art\u00edstica - Sieglinde Wittwer - watercolor_SW1","description":"Exposi\u00e7\u00f5es, Workshops, Ateliers. Resid\u00eancias para artistas e alojamento criativo. Rua Damasceno Monteiro, 12 Lisboa, Portugal Sieglinde Wittwer - watercolor_SW1 - HANGAR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg","og_locale":"en_US","og_type":"article","og_title":"HANGAR - Centro de Investiga\u00e7\u00e3o Art\u00edstica - Sieglinde Wittwer - watercolor_SW1","og_description":"Exposi\u00e7\u00f5es, Workshops, Ateliers. Resid\u00eancias para artistas e alojamento criativo. Rua Damasceno Monteiro, 12 Lisboa, Portugal Sieglinde Wittwer - watercolor_SW1 - HANGAR","og_url":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg","og_site_name":"HANGAR","og_image":[{"width":1533,"height":1080,"url":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg","url":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg","name":"HANGAR - Centro de Investiga\u00e7\u00e3o Art\u00edstica - Sieglinde Wittwer - watercolor_SW1","isPartOf":{"@id":"https:\/\/hangar.com.pt\/#website"},"datePublished":"2024-06-25T19:40:54+00:00","dateModified":"2024-06-25T19:40:54+00:00","description":"Exposi\u00e7\u00f5es, Workshops, Ateliers. Resid\u00eancias para artistas e alojamento criativo. Rua Damasceno Monteiro, 12 Lisboa, Portugal Sieglinde Wittwer - watercolor_SW1 - HANGAR","breadcrumb":{"@id":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/hangar.com.pt\/"},{"@type":"ListItem","position":2,"name":"Sieglinde Wittwer","item":"https:\/\/hangar.com.pt\/en\/sieglinde-wittwer\/"},{"@type":"ListItem","position":3,"name":"Sieglinde Wittwer &#8211; watercolor_SW1"}]},{"@type":"WebSite","@id":"https:\/\/hangar.com.pt\/#website","url":"https:\/\/hangar.com.pt\/","name":"HANGAR","description":"Centro de Investiga\u00e7\u00e3o Art\u00edstica","publisher":{"@id":"https:\/\/hangar.com.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hangar.com.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hangar.com.pt\/#organization","name":"HANGAR","url":"https:\/\/hangar.com.pt\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hangar.com.pt\/#\/schema\/logo\/image\/","url":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2017\/03\/Hangar-Logo-02_SMALL_Mail.jpg","contentUrl":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2017\/03\/Hangar-Logo-02_SMALL_Mail.jpg","width":300,"height":164,"caption":"HANGAR"},"image":{"@id":"https:\/\/hangar.com.pt\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"1533\" height=\"1080\" src=\"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg 1533w, https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1-600x423.jpeg 600w, https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1-768x541.jpeg 768w\" sizes=\"auto, (max-width: 1533px) 100vw, 1533px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1533,"height":1080,"file":"2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg","filesize":246751,"sizes":{"woocommerce_thumbnail":{"file":"Sieglinde-Wittwer-watercolor_SW1-399x532.jpeg","width":399,"height":532,"filesize":19755,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1-399x532.jpeg"},"woocommerce_gallery_thumbnail":{"file":"Sieglinde-Wittwer-watercolor_SW1-150x150.jpeg","width":150,"height":150,"filesize":3522,"mime_type":"image\/jpeg","source_url":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1-150x150.jpeg"},"woocommerce_single":{"file":"Sieglinde-Wittwer-watercolor_SW1-600x423.jpeg","width":600,"height":423,"filesize":24668,"mime_type":"image\/jpeg","source_url":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1-600x423.jpeg"},"thumbnail":{"file":"Sieglinde-Wittwer-watercolor_SW1-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1-150x150.jpeg"},"medium_large":{"file":"Sieglinde-Wittwer-watercolor_SW1-768x541.jpeg","width":768,"height":541,"mime_type":"image\/jpeg","source_url":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1-768x541.jpeg"},"shop_catalog":{"file":"Sieglinde-Wittwer-watercolor_SW1-399x532.jpeg","width":399,"height":532,"mime_type":"image\/jpeg","source_url":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1-399x532.jpeg"},"shop_single":{"file":"Sieglinde-Wittwer-watercolor_SW1-600x423.jpeg","width":600,"height":423,"mime_type":"image\/jpeg","source_url":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1-600x423.jpeg"},"shop_thumbnail":{"file":"Sieglinde-Wittwer-watercolor_SW1-100x100.jpeg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1-100x100.jpeg"},"full":{"file":"Sieglinde-Wittwer-watercolor_SW1.jpeg","width":1533,"height":1080,"mime_type":"image\/jpeg","source_url":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":25975,"source_url":"https:\/\/hangar.com.pt\/wp-content\/uploads\/2024\/06\/Sieglinde-Wittwer-watercolor_SW1.jpeg","filename":"Sieglinde-Wittwer-watercolor_SW1.jpeg","filesize":246751,"_links":{"self":[{"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/media\/25981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/users\/14"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":25975,"href":"https:\/\/hangar.com.pt\/en\/wp-json\/wp\/v2\/posts\/25975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}